{"id":9949,"count":1,"description":"","link":"https:\/\/www.motivacao.org\/blog\/tag\/os-declarados-corruptos-oportunistas-terao-o-universo-a-conspirar-na-transparencia-dos-seus-atos-futuros-que-poderao-desencadear-novas-denuncias-ou-quem-sabe-ate-vir-a-fazer-com-que-brotem-decisoes-co","name":"os declarados corruptos oportunistas ter\u00e3o o universo a conspirar na transpar\u00eancia dos seus atos futuros que poder\u00e3o desencadear novas den\u00fancias ou quem sabe at\u00e9 vir a fazer com que brotem decis?","slug":"os-declarados-corruptos-oportunistas-terao-o-universo-a-conspirar-na-transparencia-dos-seus-atos-futuros-que-poderao-desencadear-novas-denuncias-ou-quem-sabe-ate-vir-a-fazer-com-que-brotem-decisoes-co","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.motivacao.org\/blog\/wp-json\/wp\/v2\/tags\/9949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.motivacao.org\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.motivacao.org\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.motivacao.org\/blog\/wp-json\/wp\/v2\/posts?tags=9949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}